{"id":18659,"date":"2025-07-03T15:21:12","date_gmt":"2025-07-03T14:21:12","guid":{"rendered":"https:\/\/avmaison.fr\/?page_id=18659"},"modified":"2025-07-16T19:54:28","modified_gmt":"2025-07-16T18:54:28","slug":"terms","status":"publish","type":"page","link":"https:\/\/avmaison.fr\/fr\/terms\/","title":{"rendered":"Conditions g\u00e9n\u00e9rales"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"18659\" class=\"elementor elementor-18659\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cf5d3ac e-flex e-con-boxed e-con e-parent\" data-id=\"cf5d3ac\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4242852 elementor-widget elementor-widget-spacer\" data-id=\"4242852\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-85b40a2 elementor-widget elementor-widget-heading\" data-id=\"85b40a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Conditions g\u00e9n\u00e9rales<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7003de7 elementor-widget elementor-widget-text-editor\" data-id=\"7003de7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ce n'est pas une lecture passionnante. C'est probablement ennuyeux. Mais veuillez lire attentivement les conditions d'utilisation avant de commencer \u00e0 utiliser le site Web. Ne vous laissez pas intimider par le langage utilis\u00e9, il est l\u00e0 pour notre protection mutuelle.<\/p><h4>Politique de confidentialit\u00e9<\/h4><p>La fourniture de vos informations personnelles via le site Web est r\u00e9gie par notre politique de confidentialit\u00e9 disponible \u00e0 l'adresse \/privacy-policy (la \u00ab Politique de confidentialit\u00e9 \u00bb).<\/p><p><b>EN ACC\u00c9DANT \u00c0 CE SITE WEB ET EN L'UTILISANT, VOUS :<br \/>J'ACCEPTE ET JE M'ENGAGE \u00c0 RESPECTER LES PR\u00c9SENTES CONDITIONS D'UTILISATION ;<\/b><\/p><p>Ce service est exploit\u00e9 par Gary Sheehan (nous, notre ou nos) sous le nom avmaison.fr (le \u00ab site Web \u00bb). Je suis enregistr\u00e9 en France sous le num\u00e9ro SIRET 83328975400016 aupr\u00e8s du Greffe : RCS Agen.  Mon bureau est situ\u00e9 au 936 Route de Douzain, Lalandusse, 47330.<\/p><p>1.    Veuillez lire attentivement les pr\u00e9sentes conditions g\u00e9n\u00e9rales (les \u00ab Conditions \u00bb). En acc\u00e9dant \u00e0 notre site Web et \u00e0 son contenu et ses fonctionnalit\u00e9s (y compris, sans s'y limiter, les jeux, widgets, lecteurs multim\u00e9dias int\u00e9grables et flux RSS) (collectivement, nos Services), et en les utilisant, vous indiquez que vous acceptez les pr\u00e9sentes Conditions, la Politique de confidentialit\u00e9, le Code de conduite et tout autre avis, directive et r\u00e8gle que nous publions de temps \u00e0 autre sur nos Services (chacun d'entre eux \u00e9tant int\u00e9gr\u00e9 aux Conditions par cette r\u00e9f\u00e9rence). La Politique de confidentialit\u00e9 et le Code de conduite sont accessibles \u00e0 partir des liens situ\u00e9s au bas de nos pages web.<\/p><p>2.    Si vous n'acceptez pas les pr\u00e9sentes Conditions, veuillez ne pas acc\u00e9der \u00e0 nos Services ni les utiliser.<\/p><p>3.    Nous pouvons mettre \u00e0 jour les pr\u00e9sentes Conditions \u00e0 tout moment. Veuillez consulter r\u00e9guli\u00e8rement les Conditions afin de vous tenir inform\u00e9 de toute modification. En continuant \u00e0 acc\u00e9der \u00e0 nos Services et\/ou \u00e0 les utiliser apr\u00e8s que des modifications ont \u00e9t\u00e9 apport\u00e9es aux Conditions, vous acceptez d'\u00eatre l\u00e9galement li\u00e9 par les Conditions mises \u00e0 jour et\/ou modifi\u00e9es. En continuant \u00e0 utiliser le Site Web apr\u00e8s la publication des Conditions d'utilisation r\u00e9vis\u00e9es, vous acceptez et approuvez les modifications. Vous \u00eates tenu de consulter cette page chaque fois que vous acc\u00e9dez \u00e0 ce site Web afin de prendre connaissance de toute modification, car celles-ci vous engagent.<\/p><h4>Utilisation de nos services<\/h4><p>Vous acceptez d'utiliser nos Services uniquement \u00e0 des fins l\u00e9gales et d'une mani\u00e8re qui ne porte pas atteinte aux droits d'autrui, ne restreint ni n'emp\u00eache l'utilisation et la jouissance de nos Services par quiconque, et ce, dans le respect constant des pr\u00e9sentes Conditions et de toutes les lois et r\u00e9glementations applicables.<br \/>En acc\u00e9dant \u00e0 nos Services, vous acceptez de n'acc\u00e9der \u00e0 leur contenu qu'\u00e0 des fins personnelles et non commerciales, et non \u00e0 des fins commerciales ou autres, y compris la publicit\u00e9 ou la vente de biens ou de services. Vous acceptez \u00e9galement de ne pas adapter, modifier ou cr\u00e9er des \u0153uvres d\u00e9riv\u00e9es \u00e0 partir du contenu de nos Services, sauf pour votre usage personnel et non commercial. Vous devrez obtenir notre autorisation \u00e9crite pr\u00e9alable si vous souhaitez utiliser le contenu de nos Services \u00e0 d'autres fins.<br \/>De temps \u00e0 autre, nous pouvons mettre certaines parties de nos Services (y compris, sans s'y limiter, les forums ou les communaut\u00e9s) ou l'ensemble de nos Services \u00e0 la disposition exclusive des utilisateurs qui se sont inscrits aupr\u00e8s de nous. Si vous choisissez ou si vous recevez un code d'identification utilisateur, un mot de passe ou toute autre information dans le cadre de nos proc\u00e9dures de s\u00e9curit\u00e9, vous devez traiter ces informations comme confidentielles et ne les divulguer \u00e0 aucun tiers. Toutes les informations personnelles qui nous sont fournies dans le cadre de ce processus d'inscription et\/ou de toute autre interaction avec nos Services seront collect\u00e9es, stock\u00e9es et utilis\u00e9es conform\u00e9ment \u00e0 notre Politique de confidentialit\u00e9. Nous nous r\u00e9servons le droit de d\u00e9sactiver \u00e0 tout moment tout code d'identification utilisateur ou mot de passe, qu'il ait \u00e9t\u00e9 choisi par vous ou attribu\u00e9 par nous, si nous estimons que vous n'avez pas respect\u00e9 l'une des dispositions des pr\u00e9sentes Conditions.<br \/>Nous ne garantissons en aucun cas que le contenu de nos Services est appropri\u00e9 ou disponible dans votre pays. Il vous incombe de vous assurer que votre utilisation de nos Services est conforme \u00e0 toutes les lois et r\u00e9glementations locales applicables.<\/p><h4><br \/>Droits de propri\u00e9t\u00e9 intellectuelle<\/h4><p>1.    Toutes les informations, donn\u00e9es, textes, documents, graphiques, logos, dessins, images, photos, vid\u00e9os, podcasts, blogs, flux RSS, widgets, lecteurs multim\u00e9dias int\u00e9grables, logiciels, fonctionnalit\u00e9s interactives, publicit\u00e9s ou autres contenus, services ou mat\u00e9riels (ou toute partie de ceux-ci) accessibles sur nos Services (Mat\u00e9riels) sont prot\u00e9g\u00e9s par des droits d'auteur, des marques commerciales, des droits sur les bases de donn\u00e9es et d'autres droits de propri\u00e9t\u00e9 intellectuelle et sont d\u00e9tenus ou conc\u00e9d\u00e9s sous licence par nous ou sont utilis\u00e9s par nous conform\u00e9ment \u00e0 la l\u00e9gislation ou \u00e0 la r\u00e9glementation applicable. Aucune disposition des pr\u00e9sentes ne saurait \u00eatre interpr\u00e9t\u00e9e comme conf\u00e9rant, par implication, pr\u00e9clusion ou autrement, une licence ou un droit d'utiliser les Mat\u00e9riels autrement que dans les conditions autoris\u00e9es par les pr\u00e9sentes Conditions.<\/p><p>2.    Sauf autorisation expresse dans nos Services, vous vous engagez \u00e0 ne pas copier, stocker sur quelque support que ce soit (y compris sur tout autre site web), distribuer, transmettre, retransmettre, republier, diffuser, modifier ou montrer en public toute partie de nos Services sans notre autorisation \u00e9crite pr\u00e9alable (et le consentement \u00e9crit pr\u00e9alable du propri\u00e9taire des droits de propri\u00e9t\u00e9 intellectuelle concern\u00e9s, le cas \u00e9ch\u00e9ant).<\/p><h4>Contributions des utilisateurs \u00e0 nos services<\/h4><p>VEUILLEZ LIRE ATTENTIVEMENT CETTE SECTION AVANT DE T\u00c9L\u00c9CHARGER OU DE TRANSMETTRE DE QUELQUE MANI\u00c8RE QUE CE SOIT DU CONTENU SUR LE SITE. SI VOUS NE SOUHAITEZ PAS NOUS ACCORDER LES AUTORISATIONS PR\u00c9VUES DANS LES PR\u00c9SENTES CONDITIONS, VEUILLEZ NE PAS SOUMETTRE VOTRE CONTRIBUTION AU SITE.<\/p><p>1.    Nous pouvons, d\u00e8s \u00e0 pr\u00e9sent ou \u00e0 l'avenir, permettre aux utilisateurs de transmettre et\/ou de soumettre (soumettre) des contributions (y compris, sans limitation, tout texte, photographie, graphique, mat\u00e9riel vid\u00e9o ou audio) \u00e0 nos Services (Contributions des utilisateurs).<\/p><p>2.    Chaque fois que vous utilisez une fonctionnalit\u00e9 qui vous permet de soumettre des Contributions d'utilisateur ou d'entrer en contact avec d'autres utilisateurs de nos Services, vous devez vous conformer aux normes de contenu \u00e9nonc\u00e9es dans le Code de conduite. Vous vous engagez \u00e0 ce que toute Contribution d'utilisateur soit conforme au Code de conduite et vous vous engagez \u00e0 nous rembourser int\u00e9gralement tous les frais r\u00e9sultant du non-respect de votre engagement.<\/p><p>3.    Vous restez propri\u00e9taire des droits d'auteur sur toute Contribution utilisateur originale que vous soumettez. En soumettant une Contribution utilisateur \u00e0 l'un de nos Services (y compris, sans limitation, tout forum, blog, r\u00e9seau social, page de discussion, album photo ou fonctionnalit\u00e9 de t\u00e9l\u00e9chargement de vid\u00e9os) et en contrepartie de la possibilit\u00e9 que nous vous offrons de t\u00e9l\u00e9charger toute Contribution utilisateur (que vous reconnaissez comme un avantage suffisant pour vous), vous nous accordez irr\u00e9vocablement et inconditionnellement, \u00e0 titre gratuit, une licence non exclusive, libre de droits, sous-licenciable, sur l'ensemble des droits, titres et int\u00e9r\u00eats relatifs \u00e0 cette Contribution d'utilisateur, afin que nous et tout successeur puissions utiliser la Contribution d'utilisateur de quelque mani\u00e8re que ce soit, y compris, sans limitation, le droit de copier, reproduire, modifier, \u00e9diter, adapter, reformater, traduire, cr\u00e9er des \u0153uvres d\u00e9riv\u00e9es, incorporer dans d'autres \u0153uvres, transmettre, distribuer, ex\u00e9cuter, diffuser, commercialiser et rendre autrement accessible au public cette Contribution d'utilisateur (en tout ou en partie ou des copies de celle-ci) sous tout format ou support actuellement connu ou d\u00e9velopp\u00e9 \u00e0 l'avenir pendant toute la dur\u00e9e de validit\u00e9 de ces droits (y compris tous les renouvellements, r\u00e9activations, r\u00e9versions et prolongations de ceux-ci) et par la suite dans toute la mesure possible \u00e0 perp\u00e9tuit\u00e9.<\/p><p>4.    L'autorisation que vous nous avez accord\u00e9e n'est pas exclusive et vous pouvez donc continuer \u00e0 utiliser la Contribution utilisateur de quelque mani\u00e8re que ce soit et sur tout support, y compris en autorisant d'autres personnes \u00e0 l'utiliser, \u00e0 condition que cette utilisation n'interf\u00e8re pas avec les droits que vous nous avez accord\u00e9s ni ne les porte atteinte.<\/p><p>5.    Vous nous autorisez \u00e0 accorder, et nous accordons par la pr\u00e9sente \u00e0 chaque utilisateur de nos Services, une licence non exclusive pour visualiser, \u00e9couter, lire, diffuser, t\u00e9l\u00e9charger, cr\u00e9er des liens vers et acc\u00e9der de toute autre mani\u00e8re \u00e0 vos Contributions d'utilisateur \u00e0 nos Services par le biais de nos Services, et pour utiliser ces Contributions d'utilisateur comme le permettent les fonctionnalit\u00e9s de nos Services et conform\u00e9ment aux pr\u00e9sentes Conditions.<\/p><p>6.    Vous \u00eates seul responsable de vos Contributions d'utilisateur et des cons\u00e9quences de leur soumission \u00e0 nos Services. Vous vous engagez \u00e0 :<\/p><p>(a) la Contribution utilisateur est votre \u0153uvre originale et vous d\u00e9tenez l'int\u00e9gralit\u00e9 des droits, titres et int\u00e9r\u00eats relatifs \u00e0 la Contribution utilisateur et\/ou vous disposez de toutes les licences, droits, consentements et autorisations n\u00e9cessaires pour utiliser et nous autoriser \u00e0 utiliser tous les droits de propri\u00e9t\u00e9 intellectuelle (y compris, sans limitation, les droits d'auteur) relatifs \u00e0 cette Contribution utilisateur afin de nous permettre d'utiliser la Contribution utilisateur de la mani\u00e8re pr\u00e9vue par les pr\u00e9sentes Conditions ;<\/p><p>(b) aucun \u00e9l\u00e9ment de la Contribution de l'utilisateur n'est diffamatoire, obsc\u00e8ne, ind\u00e9cent, pornographique, sexuellement explicite, harcelant, mena\u00e7ant ou offensant, n'incite \u00e0 la haine raciale, culturelle ou religieuse, n'usurpe l'identit\u00e9 ou ne semble usurper l'identit\u00e9 d'une autre personne, ne constitue un outrage au tribunal, ne viole aucune loi ou r\u00e9glementation, n'encourage aucun comportement qui constituerait une infraction p\u00e9nale ou engagerait la responsabilit\u00e9 civile et\/ou n'est autrement r\u00e9pr\u00e9hensible et\/ou ne constitue une violation d'aucune loi ou r\u00e9glementation applicable ;<\/p><p>(c) vous ne collecterez, n'obtiendrez, ne compilerez, ne rassemblerez, ne transmettrez, ne reproduirez, ne supprimerez, ne modifierez, ne consulterez ni n'afficherez aucun mat\u00e9riel, aucune donn\u00e9e ou aucune information, qu'ils soient personnellement identifiables ou non, publi\u00e9s par ou concernant toute autre personne, soci\u00e9t\u00e9 ou entreprise, en relation avec votre Contribution d'utilisateur ou en relation avec votre utilisation de nos Services, sauf si vous avez obtenu l'autorisation expresse et pr\u00e9alable de cette autre personne (ou de son parent ou tuteur si cette autre personne est \u00e2g\u00e9e de moins de 16 ans), soci\u00e9t\u00e9 ou entreprise concern\u00e9e.<\/p><p>(d) la Contribution de l'utilisateur ne contient aucun virus, fichier corrompu, programme de suppression automatique, ver informatique ou autre code malveillant con\u00e7u pour interrompre, d\u00e9truire ou limiter la fonctionnalit\u00e9 ou perturber tout logiciel, mat\u00e9riel, t\u00e9l\u00e9communications, r\u00e9seaux, serveurs ou autres \u00e9quipements, ni aucun logiciel publicitaire, logiciel espion, cheval de Troie ou tout autre mat\u00e9riel con\u00e7u pour endommager, interf\u00e9rer avec, intercepter ou exproprier de mani\u00e8re abusive des donn\u00e9es ou des informations personnelles ;<\/p><p>(e) vous ne devez en aucun cas falsifier l'en-t\u00eate d'un paquet TCP\/IP ou une partie des informations contenues dans l'en-t\u00eate d'une Contribution d'utilisateur, pour quelque raison que ce soit ;<\/p><p>(f) vous ne devez pas soumettre de contenu ni effectuer d'actions qui entra\u00eenent la transmission de courriers ind\u00e9sirables, de cha\u00eenes de lettres, d'enqu\u00eates, de concours, de syst\u00e8mes de vente pyramidale, de messages dupliqu\u00e9s ou non sollicit\u00e9s, ou ce que l'on appelle le \u00ab spamming \u00bb et le \u00ab phishing \u00bb ; et<\/p><p>(g) nous ne serons pas tenus de verser ou d'engager des sommes \u00e0 toute personne ou entit\u00e9 \u00e0 la suite de notre utilisation ou exploitation de toute Contribution d'utilisateur.<\/p><p>7.    Vous renoncez par la pr\u00e9sente \u00e0 tous les droits moraux ou droits similaires existant actuellement ou cr\u00e9\u00e9s \u00e0 l'avenir dans n'importe quelle partie du monde en ce qui concerne toute Contribution d'utilisateur et vous nous accordez le droit non exclusif et libre de redevance de Studios Distribution d'utiliser tout nom, nom d'utilisateur, pseudonyme, image, photographie, signature et\/ou mat\u00e9riel biographique que vous nous avez soumis.<\/p><p>8.    Vous vous engagez \u00e0 accomplir, et \u00e0 faire en sorte que tout tiers concern\u00e9 accomplisse, tous les actes suppl\u00e9mentaires et \u00e0 signer et remettre tous les autres documents que nous pourrions raisonnablement demander afin de confirmer les licences et les droits accord\u00e9s en vertu des pr\u00e9sentes Conditions.<\/p><p>9.    Toutes les contributions des utilisateurs seront consid\u00e9r\u00e9es comme non confidentielles et nous avons le droit d'utiliser, de copier, de distribuer et de divulguer \u00e0 des tiers tout mat\u00e9riel de ce type \u00e0 quelque fin que ce soit. Nous avons \u00e9galement le droit de divulguer des informations pertinentes \u00e0 tout tiers qui pr\u00e9tend que tout mat\u00e9riel publi\u00e9 ou t\u00e9l\u00e9charg\u00e9 par vous sur notre site constitue une violation de ses droits de propri\u00e9t\u00e9 intellectuelle, de son droit \u00e0 la vie priv\u00e9e ou de toute loi ou r\u00e9glementation britannique ou autre applicable.<\/p><h4>Enl\u00e8vement des mat\u00e9riaux<\/h4><p>1.    Nous sommes en droit, \u00e0 notre discr\u00e9tion, mais sans y \u00eatre oblig\u00e9s, (a) d'examiner activement les Contributions des utilisateurs \u00e0 nos Services ; et\/ou (b) de supprimer toute Contribution d'utilisateur soumise \u00e0 nos Services par vous ou tout autre utilisateur si, \u00e0 notre avis, cette Contribution d'utilisateur n'est pas conforme aux pr\u00e9sentes Conditions.<\/p><p>2.    Nous nous r\u00e9servons le droit, \u00e0 notre seule discr\u00e9tion, \u00e0 tout moment, sans responsabilit\u00e9 et avec ou sans pr\u00e9avis (a) de ne pas publier toute Contribution d'utilisateur sur nos Services ; (b) de supprimer, suspendre ou d\u00e9sactiver l'acc\u00e8s \u00e0 toute Contribution d'utilisateur ; (c) de r\u00e9voquer votre inscription (le cas \u00e9ch\u00e9ant) et votre droit d'acc\u00e9der et\/ou d'utiliser nos Services ou de soumettre toute Contribution d'utilisateur ; et (d) d'utiliser tous les moyens technologiques, juridiques, op\u00e9rationnels ou autres disponibles pour faire respecter les pr\u00e9sentes Conditions, y compris, sans limitation, le blocage d'adresses IP sp\u00e9cifiques ou la d\u00e9sactivation de votre inscription et\/ou de votre nom d'utilisateur et mot de passe (le cas \u00e9ch\u00e9ant).<\/p><p>3.    Si vous \u00eates titulaire de droits (ou mandataire agissant pour le compte d'un titulaire de droits) et estimez qu'un contenu (y compris toute Contribution d'utilisateur) apparaissant sur nos Services porte atteinte \u00e0 vos droits et souhaitez que nous le supprimions ou que nous suspendions ou d\u00e9sactivions l'acc\u00e8s \u00e0 celui-ci, veuillez envoyer un avis par e-mail avec pour objet \u00ab Demande de suppression \u00bb \u00e0 l'adresse e-mail g\u00e9n\u00e9rale indiqu\u00e9e sur la page \u00ab Contactez-nous \u00bb du site Web sur lequel le contenu appara\u00eet.<\/p><p>Dans votre e-mail, vous devez nous fournir les informations suivantes :<\/p><p>(a)  les d\u00e9tails du contenu que vous estimez \u00eatre en infraction ou qui fait l'objet d'une activit\u00e9 illicite, ainsi que les informations raisonnablement suffisantes pour nous permettre de localiser ce contenu (y compris une URL et\/ou une capture d'\u00e9cran) ;<\/p><p>(b)  des informations raisonnablement suffisantes pour nous permettre de vous contacter, telles qu'une adresse postale, un num\u00e9ro de t\u00e9l\u00e9phone et, si disponible, une adresse \u00e9lectronique ; et<\/p><p>(c)  une d\u00e9claration de votre part indiquant que :<\/p><p>(d) vous \u00eates le titulaire des droits ou \u00eates d\u00fbment autoris\u00e9 \u00e0 agir au nom du titulaire des droits ;<\/p><p>(e)  vous estimez de bonne foi que l'utilisation du contenu faisant l'objet de la plainte n'est pas autoris\u00e9e par le titulaire des droits, son repr\u00e9sentant ou la loi ; et<\/p><p>(f)  les informations contenues dans la notification sont v\u00e9ridiques et exactes.<\/p><h4>Confiance accord\u00e9e aux informations fournies par nos Services<\/h4><p>1.    Les informations publi\u00e9es via nos Services sont uniquement destin\u00e9es \u00e0 fournir des informations g\u00e9n\u00e9rales et ne constituent en aucun cas des conseils sur lesquels il convient de se fier. Nous ne garantissons pas que les Contenus sont exacts ou exempts d'erreurs et nous d\u00e9clinons toute responsabilit\u00e9 d\u00e9coulant de la confiance accord\u00e9e \u00e0 tout contenu de nos Services par vous-m\u00eame ou par toute personne pouvant \u00eatre inform\u00e9e du contenu de nos Services.<\/p><p>2.    Vous reconnaissez que lorsque vous utilisez nos Services, vous pouvez \u00eatre expos\u00e9 \u00e0 des Contenus provenant de diverses sources et que nous ne sommes pas responsables du contenu, de la v\u00e9racit\u00e9, de l'exactitude, de l'utilit\u00e9 ou de la s\u00e9curit\u00e9 de ces Contenus. Nous n'approuvons aucune Contribution d'utilisateur ni aucune opinion, recommandation ou conseil exprim\u00e9 dans une Contribution d'utilisateur et nous d\u00e9clinons toute responsabilit\u00e9 en rapport avec ces Contributions d'utilisateur ou tout autre contenu.<\/p><p>3.    Nous nous effor\u00e7ons de mettre \u00e0 jour r\u00e9guli\u00e8rement nos Services et pouvons en modifier le contenu \u00e0 tout moment. Nous pouvons suspendre l'acc\u00e8s \u00e0 nos Services ou les fermer ind\u00e9finiment \u00e0 tout moment, \u00e0 notre seule discr\u00e9tion. Les Documents peuvent \u00eatre obsol\u00e8tes \u00e0 tout moment et nous ne sommes pas tenus de les mettre \u00e0 jour.<\/p><h4>Garanties et clause de non-responsabilit\u00e9<\/h4><p>1.    Nos Services sont fournis \u00ab TELS QUELS \u00bb et \u00ab SELON DISPONIBILIT\u00c9 \u00bb, sans aucune d\u00e9claration ni garantie d'aucune sorte. Dans toute la mesure permise par la loi applicable, nous d\u00e9clinons toute garantie, condition et autre modalit\u00e9 de quelque nature que ce soit, expresse ou implicite, en rapport avec nos services et votre utilisation de nos services (y compris, sans limitation, en ce qui concerne la qualit\u00e9 satisfaisante, l'ad\u00e9quation \u00e0 un usage particulier, la non-contrefa\u00e7on, la compatibilit\u00e9, la s\u00e9curit\u00e9 et l'exactitude).<\/p><p>2.    Nous ne garantissons pas que les fonctions contenues dans les \u00e9l\u00e9ments de nos services seront ininterrompues ou exemptes d'erreurs, que les d\u00e9fauts seront corrig\u00e9s ou que nos services ou les serveurs qui les rendent disponibles sont exempts de virus ou de bogues.<\/p><h4>Limitation de responsabilit\u00e9<\/h4><p>1.\u00a0\u00a0\u00a0 We accept no liability in respect of any User Contributions submitted by any of our users. Your use of our Services, the Materials and\/or any User Contributions is entirely at your own risk.<\/p><p>2.\u00a0\u00a0\u00a0 To the fullest extent permitted by law, we, and third parties connected to us hereby expressly exclude any liability for any direct, indirect, consequential, special or exemplary loss or damage (whether such losses were foreseen, foreseeable, known or otherwise) arising from, out of or in connection with the use of our Services, including without limitation: (a) injury and\/or damage to persons or property as a result of any statement, including any actual or alleged defamatory statement; (b) losses suffered by any third party, including infringement of any intellectual property or privacy rights; (c) loss of data; (d) loss of revenue or anticipated profits; (e) loss of business or contracts; (f) loss of opportunity; (g) loss of anticipated savings; (h) wasted management or office time; or (i) loss of goodwill or injury to reputation.<\/p><p>3.\u00a0\u00a0\u00a0 This does not affect our liability for death or personal injury arising from our negligence, fraudulent misrepresentation or misrepresentation as to a fundamental matter, nor any other liability which cannot be excluded or limited under applicable laws or regulations.<\/p><p>4.\u00a0\u00a0\u00a0 We shall not be responsible for any breach of these Terms caused by circumstances beyond our control.<\/p><h4>Reimbursement<\/h4><p>1.    Vous acceptez de nous rembourser int\u00e9gralement, ainsi que nos dirigeants, administrateurs, employ\u00e9s, agents, repr\u00e9sentants, conc\u00e9dants de licence, fournisseurs et prestataires de services op\u00e9rationnels, sur demande, pour toutes les r\u00e9clamations, actions, proc\u00e9dures, demandes, dommages, pertes, responsabilit\u00e9s, co\u00fbts et d\u00e9penses subis ou raisonnablement engag\u00e9s par nous \u00e0 la suite de, ou en relation avec, votre acc\u00e8s et votre utilisation de nos Services autrement que conform\u00e9ment aux pr\u00e9sentes Conditions ou \u00e0 toute loi ou r\u00e9glementation applicable.<\/p><h4>Virus, piratage informatique et autres infractions<\/h4><p>1.    Vous ne devez pas utiliser nos Services de mani\u00e8re abusive en introduisant, transmettant ou organisant l'envoi de virus, de fichiers corrompus, de robots d'annulation, de chevaux de Troie, de vers, de bombes logiques ou temporelles, d'enregistreurs de frappe, de logiciels espions, de logiciels publicitaires ou de tout autre mat\u00e9riel con\u00e7u pour nuire au fonctionnement de tout logiciel, mat\u00e9riel informatique ou \u00e9quipement de t\u00e9l\u00e9communications, ou pour interf\u00e9rer avec, intercepter ou exproprier de mani\u00e8re abusive des donn\u00e9es ou des informations personnelles. Vous ne devez pas tenter d'obtenir un acc\u00e8s non autoris\u00e9 \u00e0 nos Services, aux serveurs sur lesquels ils sont stock\u00e9s ou \u00e0 tout serveur, ordinateur ou base de donn\u00e9es connect\u00e9 \u00e0 nos Services. Vous ne devez pas attaquer nos Services via un d\u00e9ni de service, un d\u00e9ni de service distribu\u00e9 ou tout autre type d'attaque.<\/p><p>2.    Nous ne serons pas responsables des pertes ou dommages caus\u00e9s par une attaque par d\u00e9ni de service distribu\u00e9, des virus ou tout autre mat\u00e9riel technologiquement nuisible qui pourrait infecter votre \u00e9quipement informatique, vos programmes informatiques, vos donn\u00e9es ou tout autre mat\u00e9riel propri\u00e9taire en raison de votre utilisation de nos Services, du t\u00e9l\u00e9chargement de tout Mat\u00e9riel sur nos Services ou de tout mat\u00e9riel sur tout autre site web li\u00e9 \u00e0 ceux-ci.<\/p><h4>Liens vers et depuis nos Services<\/h4><p><b>Liens depuis nos services<\/b><\/p><p>1.    Nous n'avons aucun contr\u00f4le sur le contenu ou la disponibilit\u00e9 des sites tiers auxquels vous pouvez acc\u00e9der via nos Services, et ces liens sont fournis \u00e0 titre informatif uniquement. Si vous visitez un site li\u00e9, vous le faites \u00e0 vos propres risques et il vous incombe de prendre toutes les mesures de protection n\u00e9cessaires pour vous pr\u00e9munir contre les virus ou autres \u00e9l\u00e9ments destructeurs.<\/p><p>2.    Nous n'approuvons pas et ne sommes pas responsables (directement ou indirectement) du contenu, de la publicit\u00e9, des produits, des services, des opinions exprim\u00e9es ou des informations disponibles sur les sites web tiers (y compris, sans limitation, le paiement et la livraison de tout produit ou service) ou de tout dommage, perte ou infraction caus\u00e9s par ou en relation avec votre acc\u00e8s et votre utilisation de ces sites tiers et des services disponibles. Toutes les conditions g\u00e9n\u00e9rales, garanties ou d\u00e9clarations associ\u00e9es \u00e0 toute transaction sur des sites tiers sont exclusivement entre vous et le fournisseur concern\u00e9 de ce site et\/ou de tout service concern\u00e9.<\/p><p><b>Liens vers nos services<\/b><\/p><p>1.    Vous pouvez cr\u00e9er un lien vers la page d'accueil de n'importe quel site web au sein de nos Services sans demander notre consentement \u00e9crit pr\u00e9alable, \u00c0 CONDITION que vous respectiez pleinement les pr\u00e9sentes Conditions.<\/p><p>2.    Sauf \u00e0 des fins promotionnelles sp\u00e9cifiques, vous n'\u00eates pas autoris\u00e9 \u00e0 cr\u00e9er un lien vers une partie de nos Services autre que la page d'accueil sans notre consentement \u00e9crit pr\u00e9alable (et pour \u00e9viter toute ambigu\u00eft\u00e9, ce consentement est r\u00e9put\u00e9 accord\u00e9 en ce qui concerne les flux RSS, les widgets et les lecteurs multim\u00e9dias int\u00e9grables que nous pouvons mettre \u00e0 disposition, \u00c0 CONDITION que vous les utilisiez conform\u00e9ment aux pr\u00e9sentes Conditions et \u00e0 toute autre instruction publi\u00e9e par le biais de nos Services). Nous nous r\u00e9servons le droit de retirer l'autorisation de cr\u00e9er des liens sans pr\u00e9avis. Le site web \u00e0 partir duquel vous cr\u00e9ez un lien doit respecter en tous points les normes de contenu \u00e9nonc\u00e9es dans le Code de conduite. Nos Services ne doivent pas \u00eatre encadr\u00e9s sur un autre site.<\/p><p>3.    Tout lien vers nos Services doit \u00eatre \u00e9tabli de mani\u00e8re \u00e9quitable et l\u00e9gale, sans nuire \u00e0 notre r\u00e9putation ni en tirer profit. Vous ne devez pas cr\u00e9er de lien sugg\u00e9rant une quelconque forme d'association, de repr\u00e9sentation, d'approbation ou de soutien de notre part alors qu'il n'en existe aucune. Les liens vers nos Services n'impliquent pas que nous approuvons, sommes affili\u00e9s ou associ\u00e9s \u00e0 un site li\u00e9, ni qu'un site li\u00e9 est autoris\u00e9 \u00e0 utiliser nos marques commerciales, noms commerciaux, marques, logos ou symboles de copyright ou ceux de nos affili\u00e9s ou conc\u00e9dants de licence.<\/p><p>4.    Les liens vers nos Services ne sont pas autoris\u00e9s \u00e0 partir des \u00ab sites Web exclus \u00bb suivants :<\/p><p>(a) les sites web qui incitent \u00e0 la haine, que ce soit sur la base de la race, de la religion, du sexe, de l'orientation sexuelle ou autre, ou qui encouragent, favorisent ou facilitent les comportements antisociaux ;<\/p><p>(b) les sites web qui promeuvent, encouragent ou facilitent la violence ;<\/p><p>(c)  les sites web qui discriminent un groupe social sp\u00e9cifique ou exploitent de toute autre mani\u00e8re les couches vuln\u00e9rables de la soci\u00e9t\u00e9 ;<\/p><p>(d)  les sites web qui promeuvent, facilitent ou encouragent des activit\u00e9s ill\u00e9gales ;<\/p><p>(e)  les sites web qui sont trompeurs, pornographiques, diffamatoires ou qui contiennent des contenus ill\u00e9gaux ou autrement passibles de poursuites en vertu de la loi ; ou<\/p><p>(f)  les sites web qui portent atteinte \u00e0 la vie priv\u00e9e des individus.<\/p><h4>Publicit\u00e9 et parrainage<\/h4><p>1.    Tout ou partie des Services peuvent parfois contenir des publicit\u00e9s et des parrainages. Les annonceurs et les sponsors sont tenus de s'assurer que tous les contenus soumis pour inclusion dans nos Services sont conformes aux lois, r\u00e9glementations et codes applicables, ainsi qu'aux pr\u00e9sentes Conditions. Nous ne saurions \u00eatre tenus responsables des erreurs ou inexactitudes contenues dans ces publicit\u00e9s ou contenus de parrainage.<\/p><h4>Logiciel<\/h4><p>1.    De temps \u00e0 autre, certains logiciels qui constituent notre \u0153uvre prot\u00e9g\u00e9e ou l'\u0153uvre prot\u00e9g\u00e9e de nos fournisseurs peuvent \u00eatre mis \u00e0 disposition pour t\u00e9l\u00e9chargement via nos Services. Vous \u00eates autoris\u00e9 \u00e0 utiliser le logiciel sur une base non exclusive uniquement aux fins pour lesquelles il est indiqu\u00e9. Vous ne pouvez pas utiliser le logiciel \u00e0 d'autres fins et vous ne pouvez pas le redistribuer, le vendre, le d\u00e9compiler, le d\u00e9sosser, le d\u00e9sassembler ou le traiter de quelque mani\u00e8re que ce soit.<\/p><h4>Confidentialit\u00e9<\/h4><p>1.    Toutes les informations personnelles que vous fournissez dans le cadre d'un processus d'inscription et\/ou d'autres interactions avec nos Services seront collect\u00e9es, stock\u00e9es et utilis\u00e9es conform\u00e9ment \u00e0 notre Politique de confidentialit\u00e9.<\/p><h4><span style=\"font-size: 1.5rem;\">Commandes en ligne<\/span><\/h4><p>Toutes les commandes, achats ou transactions pour la vente de biens, de produits num\u00e9riques ou d'informations effectu\u00e9s via ce site Web sont soumis aux conditions g\u00e9n\u00e9rales de vente suppl\u00e9mentaires suivantes :<\/p><p>1.    Vous acceptez que votre commande constitue une offre d'achat, conform\u00e9ment aux pr\u00e9sentes Conditions d'utilisation, de tous les biens, produits num\u00e9riques ou informations figurant dans votre commande. Toutes les commandes doivent \u00eatre accept\u00e9es par nous, faute de quoi nous ne serons pas tenus de vous vendre ces biens, produits num\u00e9riques ou informations. Nous pouvons choisir de ne pas accepter les commandes \u00e0 notre seule discr\u00e9tion, m\u00eame apr\u00e8s vous avoir envoy\u00e9 un e-mail de confirmation contenant votre num\u00e9ro de commande et les d\u00e9tails des articles que vous avez command\u00e9s ; et<\/p><p>2.    Tous les prix, remises et promotions affich\u00e9s sur ce site Web sont susceptibles d'\u00eatre modifi\u00e9s sans pr\u00e9avis. Le prix et la devise factur\u00e9s pour un produit, un produit num\u00e9rique ou une information seront ceux indiqu\u00e9s sur ce site Web au moment de la commande, sous r\u00e9serve des conditions de toute promotion ou remise applicable. Le prix et la devise factur\u00e9s seront clairement indiqu\u00e9s dans le panier avant que vous ne confirmiez votre achat. Les augmentations de prix ne s'appliqueront qu'aux commandes pass\u00e9es apr\u00e8s la date de l'augmentation. Les prix affich\u00e9s n'incluent pas les taxes ni les frais d'exp\u00e9dition et de manutention. Toutes ces taxes et tous ces frais seront ajout\u00e9s au prix total et seront d\u00e9taill\u00e9s dans votre panier et dans votre e-mail de confirmation de commande. Nous nous effor\u00e7ons d'afficher des informations pr\u00e9cises sur les prix ; toutefois, il peut arriver que nous commettions des erreurs typographiques, des inexactitudes ou des omissions involontaires concernant les prix et la disponibilit\u00e9. Nous nous r\u00e9servons le droit de corriger \u00e0 tout moment toute erreur, inexactitude ou omission et d'annuler toute commande r\u00e9sultant de tels \u00e9v\u00e9nements.<\/p><p>3.    Lorsqu'une commande indique qu'une licence est en cours d'achat :<\/p><p>4.    Toutes les utilisations sur ce site Web des termes \u00ab vendre \u00bb, \u00ab vente \u00bb, \u00ab revendre \u00bb, \u00ab revente \u00bb, \u00ab acheter \u00bb, \u00ab prix \u00bb et autres termes similaires d\u00e9signent l'achat ou la vente d'une licence ;<\/p><p>5.    Chaque produit num\u00e9rique ou information commercialis\u00e9 comme tel sur ce site Web est mis \u00e0 votre disposition et \u00e0 celle d'autres clients potentiels uniquement sous licence, et non \u00e0 des fins de vente, conform\u00e9ment aux conditions g\u00e9n\u00e9rales et restrictions de la licence Conditions d'utilisation publi\u00e9es ou mises \u00e0 votre disposition \u00e0 l'adresse \/license ;<\/p><p>6.    Vous vous engagerez \u00e0 respecter toutes les conditions g\u00e9n\u00e9rales des conditions d'utilisation de licence applicables \u00e0 tous les biens, produits num\u00e9riques ou informations que vous obtenez par le biais de ce site Web, et vous ne causerez, n'inciterez ni ne permettrez \u00e0 autrui de ne pas respecter les conditions g\u00e9n\u00e9rales des conditions d'utilisation de licence applicables aux biens, produits num\u00e9riques ou informations ; et<\/p><p>7.\u00a0\u00a0\u00a0 \u00c0 l'exception de la licence limit\u00e9e accord\u00e9e en vertu des conditions d'utilisation de la licence concern\u00e9e, rien dans les pr\u00e9sentes conditions d'utilisation n'accorde de droit, de titre ou d'int\u00e9r\u00eat (y compris toute licence) sur les droits de propri\u00e9t\u00e9 intellectuelle li\u00e9s au bien, au produit num\u00e9rique ou \u00e0 l'information, que ce soit de mani\u00e8re expresse, implicite, par estoppel ou autrement. Tous les droits, titres et int\u00e9r\u00eats li\u00e9s au bien, au produit num\u00e9rique ou \u00e0 l'information appartiennent et resteront la propri\u00e9t\u00e9 de la soci\u00e9t\u00e9 ou de ses conc\u00e9dants de licence, selon le cas.<\/p><h4>Exp\u00e9ditions et livraison.<\/h4><p>Nous organiserons l'exp\u00e9dition des marchandises \u00e0 votre adresse. Veuillez consulter la page de chaque produit pour conna\u00eetre les options de livraison sp\u00e9cifiques. Vous devrez payer tous les frais d'exp\u00e9dition et de manutention, sauf indication contraire dans la confirmation de commande.<br \/>Le titre de propri\u00e9t\u00e9 et le risque de perte vous sont transf\u00e9r\u00e9s d\u00e8s que nous remettons les produits au transporteur\/livreur. Les dates d'exp\u00e9dition et de livraison ne sont que des estimations et ne peuvent \u00eatre garanties. Nous ne sommes pas responsables des retards dans les exp\u00e9ditions.<\/p><h4 id=\"deposit\">Paiement et frais<\/h4><p>Votre commande initiale via le site web ne n\u00e9cessitera que le paiement d'un acompte.  Le solde restant pour la fourniture du forfait que vous avez command\u00e9 sera payable au photographe\/vid\u00e9aste avant la prestation du service.  Cet acompte n'est pas remboursable.  Vous devrez peut-\u00eatre \u00e9galement payer des frais de d\u00e9placement si le photographe\/vid\u00e9aste que vous avez choisi doit parcourir plus de 50 km pour se rendre \u00e0 votre propri\u00e9t\u00e9.<\/p><p>Vous devrez peut-\u00eatre acheter ou payer des frais pour acc\u00e9der \u00e0 nos services. Nous acceptons les cartes Mastercard, Visa et American Express pour tous les achats. Cependant, avmaison ne garantit pas la disponibilit\u00e9 d'un mode de paiement \u00e0 tout moment et avmaison peut ajouter, supprimer ou suspendre temporairement ou d\u00e9finitivement tout mode de paiement \u00e0 sa seule discr\u00e9tion. Vous acceptez de fournir des informations d'achat et de compte \u00e0 jour, compl\u00e8tes et exactes pour tous les achats effectu\u00e9s via le site web et de mettre \u00e0 jour rapidement les informations relatives \u00e0 votre compte et \u00e0 votre paiement, y compris votre adresse \u00e9lectronique, votre mode de paiement et la date d'expiration de votre carte de paiement, afin de finaliser vos achats et de vous contacter si n\u00e9cessaire. Toute taxe de vente applicable (TVA) sera ajout\u00e9e au prix des achats, comme nous le jugeons n\u00e9cessaire. Nous pouvons modifier les prix \u00e0 tout moment. Tous les paiements doivent \u00eatre effectu\u00e9s en euros.<\/p><p>Vous acceptez de payer tous les frais ou commissions aux prix alors en vigueur pour vos achats, et vous nous autorisez \u00e0 facturer votre prestataire de paiement choisi pour ces montants lors de votre achat.<\/p><p>Nous nous r\u00e9servons le droit de corriger toute erreur ou inexactitude dans les prix, m\u00eame si nous avons d\u00e9j\u00e0 demand\u00e9 ou re\u00e7u le paiement. Nous nous r\u00e9servons \u00e9galement le droit de refuser toute commande pass\u00e9e via le site Web.<\/p><h4>Ordre de pr\u00e9s\u00e9ance<\/h4><p>1.    En cas de conflit entre les pr\u00e9sentes Conditions et toute condition sp\u00e9cifique figurant ailleurs sur nos Services et relative \u00e0 un contenu sp\u00e9cifique (y compris le Code de conduite), cette derni\u00e8re pr\u00e9vaudra.<\/p><h4>Divisibilit\u00e9<\/h4><p>1.    Si l'une des pr\u00e9sentes Conditions est jug\u00e9e ill\u00e9gale, invalide ou inapplicable en vertu des lois d'un \u00c9tat ou d'un pays dans lequel les pr\u00e9sentes Conditions sont cens\u00e9es s'appliquer, alors, dans la mesure et dans la juridiction o\u00f9 cette condition est ill\u00e9gale, invalide ou inapplicable, elle sera supprim\u00e9e des pr\u00e9sentes Conditions et les autres Conditions resteront en vigueur, conserveront leur pleine force et leur plein effet et continueront d'\u00eatre contraignantes et applicables.<\/p><h4>Comp\u00e9tence<\/h4><p>1.    Les Conditions sont r\u00e9gies et interpr\u00e9t\u00e9es conform\u00e9ment au droit fran\u00e7ais.<\/p><h4>Litiges<\/h4><p>1.    Tout litige d\u00e9coulant de ou li\u00e9 \u00e0 nos Services sera soumis \u00e0 la comp\u00e9tence des tribunaux fran\u00e7ais.<\/p><p><i>Bravo. Tu as r\u00e9ussi, m\u00eame si c'\u00e9tait vraiment tr\u00e8s ennuyeux.<\/i><\/p><p>Derni\u00e8re mise \u00e0 jour : novembre 2024<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-22a02eb elementor-widget elementor-widget-spacer\" data-id=\"22a02eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Terms and Conditions A gripping read; it is not.\u00a0 Probably boring. But, please read the Terms of Service carefully before you start to use the Website. Don\u2019t be scared of the language, It\u2019s here for our mutual protection. Privacy Policy Your provision of personal information through the Website is governed by our privacy policy located [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"slim_seo":{"title":"Terms - avmaison.fr","description":"Terms and Conditions A gripping read; it is not.\u00a0 Probably boring. But, please read the Terms of Service carefully before you start to use the Website. Don\u2019t be"},"footnotes":""},"class_list":["post-18659","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/avmaison.fr\/fr\/wp-json\/wp\/v2\/pages\/18659","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/avmaison.fr\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/avmaison.fr\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/avmaison.fr\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/avmaison.fr\/fr\/wp-json\/wp\/v2\/comments?post=18659"}],"version-history":[{"count":16,"href":"https:\/\/avmaison.fr\/fr\/wp-json\/wp\/v2\/pages\/18659\/revisions"}],"predecessor-version":[{"id":19078,"href":"https:\/\/avmaison.fr\/fr\/wp-json\/wp\/v2\/pages\/18659\/revisions\/19078"}],"wp:attachment":[{"href":"https:\/\/avmaison.fr\/fr\/wp-json\/wp\/v2\/media?parent=18659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}